{"id":76459,"date":"2022-08-18T14:07:14","date_gmt":"2022-08-18T14:07:14","guid":{"rendered":"https:\/\/www.atlasrleye.com\/?page_id=76459"},"modified":"2024-03-20T18:18:58","modified_gmt":"2024-03-20T18:18:58","slug":"clinical-case-1","status":"publish","type":"page","link":"https:\/\/www.atlasrleye.com\/en\/wyburn-mason-syndrome\/clinical-case-1\/","title":{"rendered":"Clinical Case 1"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_custom_heading text=&#8221;RETINAL DYSTROPHIES AND SYNDROMES&#8221; font_container=&#8221;tag:h5|font_size:22px|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fatlas%2F%231636632807269-1444524b-3ed4|&#8221;][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;fas fa-eye&#8221; i_color=&#8221;custom&#8221; i_size=&#8221;lg&#8221; color=&#8221;custom&#8221; border_width=&#8221;8&#8243; add_icon=&#8221;true&#8221; css=&#8221;.vc_custom_1637080776101{margin-bottom: -5px !important;}&#8221; accent_color=&#8221;#bababa&#8221; i_custom_color=&#8221;#bababa&#8221;][vc_custom_heading text=&#8221;Wiburn-Mason Syndrome &#8211; Clinical Case 1&#8243; font_container=&#8221;tag:h1|text_align:center|color:%235f1b52&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fwyburn-mason-syndrome%2F|title:WYBURN-MASON%20SYNDROME|&#8221;]<div class=\"ult-spacer spacer-6a03d1738b8b7\" data-id=\"6a03d1738b8b7\" data-height=\"70\" data-height-mobile=\"70\" data-height-tab=\"70\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer spacer-6a03d1738b939\" data-id=\"6a03d1738b939\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div class=\"ult-spacer spacer-6a03d1738b9a1\" data-id=\"6a03d1738b9a1\" data-height=\"20\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<p style=\"font-size: 18px; text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-76492\" src=\"https:\/\/www.atlasrleye.com\/wp-content\/uploads\/2022\/08\/o01-ti02-3676-20110504-004-1-300x246.jpg\" alt=\"\" width=\"255\" height=\"209\">Fundus photograph of Wiburn-Mason Syndrome in a 40-years-old male patient. Note the tortuous retinal artery<br \/>\n<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<p style=\"text-align: justify; font-size: 18px;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-21777\" src=\"https:\/\/www.atlasrleye.com\/wp-content\/uploads\/2022\/01\/o02-ti07-3676-20110504-032-281x300.jpg\" alt=\"\" width=\"196\" height=\"209\">Fluorescein angiogram at early stage showing no leakage<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3><span style=\"color: #5f1b52;\">Evaluations<br \/>\n<\/span><\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;99&#8243; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221;][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;1st Evaluation &#8211; 17 11 2008&#8243; tab_id=&#8221;1643373639676-c3c218cd-c91c&#8221;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Fluorescein Angiography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Some macular leakage at superior macular arcade.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69616,69592,69625,69589,69619,69613,69622&#8243; img_size=&#8221;193&#215;206&#8243; css=&#8221;.vc_custom_1708276345012{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69595&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69601&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Red-free photograph showing an epiretinal membrane (LE).<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69598&#8243; img_size=&#8221;193&#215;206&#8243; css=&#8221;.vc_custom_1708276509402{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">OCT line-scan showing a macular edema.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69610&#8243; img_size=&#8221;420&#215;206&#8243; css=&#8221;.vc_custom_1708276400563{margin-top: -30px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69604&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;2nd Evaluation &#8211; postoperative &#8211; 04 03 2009&#8243; tab_id=&#8221;1661348065891-f5f0d456-af6e&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69664&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69646,69640&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">After epiretinal membrane removal.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69637,69631&#8243; img_size=&#8221;193&#215;206&#8243; css=&#8221;.vc_custom_1708276628763{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Anterior Segment Photo<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">One day after epiretinal membrane removal.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69658,69661,69655&#8243; img_size=&#8221;323&#215;206&#8243; css=&#8221;.vc_custom_1708276592012{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69649,69652&#8243; img_size=&#8221;410&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69643,69634&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;3rd Evaluation &#8211; 19 10 2009&#8243; tab_id=&#8221;1661348616094-ac7d692f-de22&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Fluorescein Angiography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69691,69703,69682,69670,69667,69676,69679,69673&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69697&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69685&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69700&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Anterior Segment Photo<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69694&#8243; img_size=&#8221;323&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69688&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;4th Evaluation &#8211; 30 09 2010&#8243; tab_id=&#8221;1661352478285-ff0493c4-e379&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69718&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69715&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69706&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69709,69712&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;5th Evaluation &#8211; 04 05 2011&#8243; tab_id=&#8221;1661352599371-415d25c1-df77&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Fluorescein Angiography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69826,69841,69736,69724,69844,69847,69832,69850,69721,69733,69838&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69829&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69745&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69835&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69799,69784,69790,69796&#8243; img_size=&#8221;307&#215;110&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69772,69808,69814,69811,69805,69817,69802,69820&#8243; img_size=&#8221;207&#215;110&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69742,69754,69793,69781,69787,69775,69748,69757,69751,69760,69766,69769,69763,69778&#8243; img_size=&#8221;307&#215;110&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;4\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69727,69730,69739&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Tonometry<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69823&#8243; img_size=&#8221;206&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;6th Evaluation &#8211; 23 11 2011&#8243; tab_id=&#8221;1661353115704-1b364a22-ab31&#8243;][vc_row_inner][vc_column_inner width=&#8221;2\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69856,69874&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69868&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/5&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69859,69865&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Perimetry<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69853,69871&#8243; img_size=&#8221;145&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69862&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;7th Evaluation &#8211; 12 06 2012&#8243; tab_id=&#8221;1661353244999-b95fc173-43de&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69892&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69904&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69898&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Nerve Fiber Analysis<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69895&#8243; img_size=&#8221;145&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69907,69916,69910,69913&#8243; img_size=&#8221;307&#215;110&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69877,69937,69922,69883,69886,69928,69919,69880,69925,69931,69934&#8243; img_size=&#8221;259&#215;110&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Anterior Segment Photo<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69889&#8243; img_size=&#8221;323&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69901&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;8th Evaluation &#8211; 02 02 2015&#8243; tab_id=&#8221;1661353889746-dcecccbb-04c4&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69955&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69949&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69946&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69943,69940&#8243; img_size=&#8221;307&#215;110&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Six years after epiretinal membrane surgery. Visual acuity: 20\/60 LE.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;69952&#8243; img_size=&#8221;251&#215;206&#8243; css=&#8221;.vc_custom_1708276662587{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;9th Evaluation &#8211; 02 02 2023&#8243; tab_id=&#8221;1710957990277-aeb23687-23cc&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;106141&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\"> Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;106133&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;106137&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">VA: 20\/15 RE, 20\/80 LE .<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;106145,106129&#8243; img_size=&#8221;307&#215;110&#8243; css=&#8221;.vc_custom_1710958493171{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row]<\/p>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading text=&#8221;RETINAL DYSTROPHIES AND SYNDROMES&#8221; font_container=&#8221;tag:h5|font_size:22px|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fatlas%2F%231636632807269-1444524b-3ed4|&#8221;][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;fas fa-eye&#8221; i_color=&#8221;custom&#8221; i_size=&#8221;lg&#8221; color=&#8221;custom&#8221; border_width=&#8221;8&#8243; add_icon=&#8221;true&#8221; css=&#8221;.vc_custom_1637080776101{margin-bottom: -5px !important;}&#8221; accent_color=&#8221;#bababa&#8221; i_custom_color=&#8221;#bababa&#8221;][vc_custom_heading text=&#8221;Wiburn-Mason Syndrome &#8211; Clinical Case 1&#8243; font_container=&#8221;tag:h1|text_align:center|color:%235f1b52&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fwyburn-mason-syndrome%2F|title:WYBURN-MASON%20SYNDROME|&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner][vc_column_text] Fundus photograph of Wiburn-Mason Syndrome in a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":73999,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-76459","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/76459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/comments?post=76459"}],"version-history":[{"count":20,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/76459\/revisions"}],"predecessor-version":[{"id":106172,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/76459\/revisions\/106172"}],"up":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/73999"}],"wp:attachment":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/media?parent=76459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}