{"id":72034,"date":"2021-12-20T13:12:01","date_gmt":"2021-12-20T13:12:01","guid":{"rendered":"https:\/\/www.atlasrleye.com\/optic-disc-drusen\/clinical-case-1\/"},"modified":"2024-01-28T12:28:24","modified_gmt":"2024-01-28T12:28:24","slug":"clinical-case-1","status":"publish","type":"page","link":"https:\/\/www.atlasrleye.com\/en\/optic-disc-drusen\/clinical-case-1\/","title":{"rendered":"Clinical Case 1"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_custom_heading text=&#8221;OPTIC NERVE DISEASES&#8221; font_container=&#8221;tag:h5|font_size:22px|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fatlas%2F%231635513667903-88e5ccf5-18e6|&#8221;][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;fas fa-eye&#8221; i_color=&#8221;custom&#8221; i_size=&#8221;lg&#8221; color=&#8221;custom&#8221; border_width=&#8221;8&#8243; add_icon=&#8221;true&#8221; css=&#8221;.vc_custom_1637080776101{margin-bottom: -5px !important;}&#8221; accent_color=&#8221;#bababa&#8221; i_custom_color=&#8221;#bababa&#8221;][vc_custom_heading text=&#8221;Optic Disc Drusen &#8211; Clinical Case 1&#8243; font_container=&#8221;tag:h1|text_align:center|color:%235f1b52&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Foptic-disc-drusen%2F|title:OPTIC%20DISC%20DRUSEN|&#8221;]<div class=\"ult-spacer spacer-6a03d34a3c55e\" data-id=\"6a03d34a3c55e\" data-height=\"70\" data-height-mobile=\"70\" data-height-tab=\"70\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer spacer-6a03d34a3c5c6\" data-id=\"6a03d34a3c5c6\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div class=\"ult-spacer spacer-6a03d34a3c628\" data-id=\"6a03d34a3c628\" data-height=\"20\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;30824&#8243; img_size=&#8221;280&#215;210&#8243; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<p style=\"font-size: 18px; text-align: justify;\"><span style=\"color: #000000;\">Autofluorescence photograph in a 70-years-old patient showing hiperautofluorescent optic disc drusen. AV: 20\/20 RE.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;30821&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify; font-size: 18px;\"><span style=\"color: #000000;\">A,B-axial line scan echogram demonstrating calcification at the optic nerve. Visual acuity: 20\/20 LE.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3><span style=\"color: #5f1b52;\">Evaluations<br \/>\n<\/span><\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;99&#8243; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221;][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;1st Evaluation &#8211; 18 12 2009&#8243; tab_id=&#8221;1639744796246-594bc4fe-4d6b&#8221;][vc_row_inner][vc_column_inner width=&#8221;5\/6&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Autofluorescence photograph of optic disc drusen. These hyaline bodies are highly autofluorescent. VA: 20\/20 RE.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30854,30863,30842&#8243; img_size=&#8221;188&#215;206&#8243; css=&#8221;.vc_custom_1706444132818{margin-top: -30px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30857&#8243; img_size=&#8221;183&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Echography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">B-scan echogram demonstrating calcifications at the optic disc.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30860&#8243; img_size=&#8221;274&#215;206&#8243; css=&#8221;.vc_custom_1706444163842{margin-top: -30px !important;}&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Anterior Segment Photo<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">LE showing cataract. The patient complains of floaters and photopsias.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30845&#8243; img_size=&#8221;323&#215;206&#8243; css=&#8221;.vc_custom_1706444449556{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1706444233537{margin-top: -30px !important;}&#8221;]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour Retinography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Fundus photograph showing a small optic disc, with drusen partially extruded, visible in the nasal and superior sectors.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30848,30851&#8243; img_size=&#8221;251&#215;206&#8243; css=&#8221;.vc_custom_1706444458303{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;2nd Evaluation &#8211; 18 01 2011&#8243; tab_id=&#8221;1639746390005-1dc334ec-42f5&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Biometry<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30866&#8243; img_size=&#8221;228&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Microperimetry<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30878&#8243; img_size=&#8221;287&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour Retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30869&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30872&#8243; img_size=&#8221;251&#215;250&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;3rd Evaluation &#8211; 28 06 2011&#8243; tab_id=&#8221;1640003126704-666ec7d7-3861&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Fluorescein Angiography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30954,30957,30881&#8243; img_size=&#8221;188&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30900,30903&#8243; img_size=&#8221;188&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30906&#8243; img_size=&#8221;188&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Macular epiretinal membrane.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30894,30897&#8243; img_size=&#8221;188&#215;206&#8243; css=&#8221;.vc_custom_1706444271800{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Echography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30884,30888&#8243; img_size=&#8221;274&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Tonometry<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30951&#8243; img_size=&#8221;206&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Macular epiretinal membrane.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30939,30942,30945,30948&#8243; img_size=&#8221;307&#215;110&#8243; css=&#8221;.vc_custom_1706444767758{margin-top: -30px !important;}&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30909,30912,30915,30918,30921,30924,30927,30930,30933,30936&#8243; img_size=&#8221;180&#215;110&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour Retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30891&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;4th Evaluation &#8211; 24 01 2012&#8243; tab_id=&#8221;1640006930519-6616e999-2fed&#8221;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Autofluorescence<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30978&#8243; img_size=&#8221;188&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30981&#8243; img_size=&#8221;188&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30975&#8243; img_size=&#8221;188&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Seven weeks after epirretinal membrane removal. VA: 20\/20 RE.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30963,30966,30969,30972&#8243; img_size=&#8221;307&#215;110&#8243; css=&#8221;.vc_custom_1706444365130{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour Retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;30960&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading text=&#8221;OPTIC NERVE DISEASES&#8221; font_container=&#8221;tag:h5|font_size:22px|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fatlas%2F%231635513667903-88e5ccf5-18e6|&#8221;][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;fas fa-eye&#8221; i_color=&#8221;custom&#8221; i_size=&#8221;lg&#8221; color=&#8221;custom&#8221; border_width=&#8221;8&#8243; add_icon=&#8221;true&#8221; css=&#8221;.vc_custom_1637080776101{margin-bottom: -5px !important;}&#8221; accent_color=&#8221;#bababa&#8221; i_custom_color=&#8221;#bababa&#8221;][vc_custom_heading text=&#8221;Optic Disc Drusen &#8211; Clinical Case 1&#8243; font_container=&#8221;tag:h1|text_align:center|color:%235f1b52&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Foptic-disc-drusen%2F|title:OPTIC%20DISC%20DRUSEN|&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;30824&#8243; img_size=&#8221;280&#215;210&#8243; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text] Autofluorescence [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":72030,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-72034","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/72034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/comments?post=72034"}],"version-history":[{"count":13,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/72034\/revisions"}],"predecessor-version":[{"id":94870,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/72034\/revisions\/94870"}],"up":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/72030"}],"wp:attachment":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/media?parent=72034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}