{"id":71865,"date":"2021-12-17T10:42:13","date_gmt":"2021-12-17T10:42:13","guid":{"rendered":"https:\/\/www.atlasrleye.com\/familial-exudative-vitreoretinopathy\/clinical-case-1\/"},"modified":"2024-10-31T12:52:24","modified_gmt":"2024-10-31T12:52:24","slug":"clinical-case-1","status":"publish","type":"page","link":"https:\/\/www.atlasrleye.com\/en\/familial-exudative-vitreoretinopathy\/clinical-case-1\/","title":{"rendered":"Clinical Case 1"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_custom_heading text=&#8221;CONGENITAL AND PEDIATRIC RETINAL DISEASES&#8221; font_container=&#8221;tag:h5|font_size:22px|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fatlas%2F%231635506431806-afc59564-1028|&#8221;][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;fas fa-eye&#8221; i_color=&#8221;custom&#8221; i_size=&#8221;lg&#8221; color=&#8221;custom&#8221; border_width=&#8221;8&#8243; css=&#8221;.vc_custom_1637080776101{margin-bottom: -5px !important;}&#8221; add_icon=&#8221;true&#8221; accent_color=&#8221;#bababa&#8221; i_custom_color=&#8221;#bababa&#8221;][vc_custom_heading text=&#8221;Familial Exudative Vitreoretinopathy &#8211; Clinical Case 1&#8243; font_container=&#8221;tag:h1|text_align:center|color:%235f1b52&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Ffamilial-exudative-vitreoretinopathy%2F|title:%20Familial%20Exudative%20Vitreoretinopathy%20|&#8221;]<div class=\"ult-spacer spacer-6a03d173d2384\" data-id=\"6a03d173d2384\" data-height=\"70\" data-height-mobile=\"70\" data-height-tab=\"70\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer spacer-6a03d173d243a\" data-id=\"6a03d173d243a\" data-height=\"10\" data-height-mobile=\"10\" data-height-tab=\"10\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div><div class=\"ult-spacer spacer-6a03d173d24f0\" data-id=\"6a03d173d24f0\" data-height=\"20\" data-height-mobile=\"20\" data-height-tab=\"20\" data-height-tab-portrait=\"\" data-height-mobile-landscape=\"\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;4959&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<p style=\"font-size: 18px; text-align: justify;\"><span style=\"color: #000000;\">Fluorescein angiogram at early phase of familial exudative vitreoretinopathy in a 6-month-old baby. He has an exudative retinal detachment.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;4958&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<p style=\"text-align: justify; font-size: 18px;\"><span style=\"color: #000000;\">Fluorescein angiogram four months later. Exsudative retinal detachment is no longer evident, retina is completely attached.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h3><span style=\"color: #5f1b52;\">Evaluations <\/span><\/h3>\n<p>[\/vc_column_text][vc_tta_accordion active_section=&#8221;99&#8243; no_fill=&#8221;true&#8221; collapsible_all=&#8221;true&#8221;][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;1st Evaluation &#8211; 20 07 2009&#8243; tab_id=&#8221;1636641179216-cb4f444c-b7b1&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Fluorescein Angiography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4966,4967,4963&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4964,4965&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;2nd Evaluation &#8211; 07 10 2009&#8243; tab_id=&#8221;1639737950297-d30d6c47-1ebd&#8221;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Fluorescein Angiography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Fluorescein angiogram after laser treatment and bevacizumab intraocular injection.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4969,4970,4973,4974,4968&#8243; img_size=&#8221;235&#215;206&#8243; css=&#8221;.vc_custom_1706398820428{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Fundus photograph after laser treatment and bevacizumab intraocular injection.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4971,4972&#8243; img_size=&#8221;251&#215;206&#8243; css=&#8221;.vc_custom_1706398876636{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;3rd Evaluation &#8211; 02 01 2012&#8243; tab_id=&#8221;1639738028656-87cac0d1-bda1&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Fluorescein Angiography<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4978,4979,4980,4981,4982,4983,4984,4975&#8243; img_size=&#8221;251&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">The retina remains attached, subretinal fibrosis is visible in the periphery.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4976,4977&#8243; img_size=&#8221;251&#215;206&#8243; css=&#8221;.vc_custom_1706398910236{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;4th Evaluation &#8211; 05 01 2015&#8243; tab_id=&#8221;1709166104677-09d151da-b182&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100212&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Red-free<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100205&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Anterior Segment Photo<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">BCVA: 20\/100 RE, 20\/100 LE. Bilateral high hyperopia.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100186,100190&#8243; img_size=&#8221;300&#215;206&#8243; css=&#8221;.vc_custom_1709166453853{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100217,100174,100178,100182&#8243; img_size=&#8221;207&#215;110&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text css=&#8221;&#8221;]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">Familial exudative vitreoretinopathy treated with laser and bevacizumab. Bilateral exudative detachment.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100194,100198&#8243; img_size=&#8221;251&#215;206&#8243; css=&#8221;.vc_custom_1709166541849{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][vc_tta_section i_icon_fontawesome=&#8221;far fa-calendar-alt&#8221; add_icon=&#8221;true&#8221; title=&#8221;5th Evaluation &#8211; 25 11 2022&#8243; tab_id=&#8221;1709166569373-15a0ea18-1815&#8243;][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Infrared<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100236,100240&#8243; img_size=&#8221;193&#215;206&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">OCT (B-Scan) longitudinal<\/p>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100253,100224,100228,100232&#8243; img_size=&#8221;207&#215;110&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"row py-1\">\n<div class=\"col-12 border-bottom border-gray-light\">\n<p style=\"font-size: 18px;\">Colour retinography<\/p>\n<div style=\"text-indent: 20px;\">\n<p style=\"font-size: 14px; text-align: justify;\"><span style=\"color: #000000;\">BCVA: 20\/100 RE, 20\/100 LE. Bilateral high hyperopia. RE: anterior polar cataract. LE: anterior capsular opacification of the lens.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;100244,100249&#8243; img_size=&#8221;251&#215;206&#8243; css=&#8221;.vc_custom_1709166643677{margin-top: -30px !important;}&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_tta_section][\/vc_tta_accordion][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading text=&#8221;CONGENITAL AND PEDIATRIC RETINAL DISEASES&#8221; font_container=&#8221;tag:h5|font_size:22px|text_align:center|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Fatlas%2F%231635506431806-afc59564-1028|&#8221;][vc_text_separator title=&#8221;&#8221; i_icon_fontawesome=&#8221;fas fa-eye&#8221; i_color=&#8221;custom&#8221; i_size=&#8221;lg&#8221; color=&#8221;custom&#8221; border_width=&#8221;8&#8243; css=&#8221;.vc_custom_1637080776101{margin-bottom: -5px !important;}&#8221; add_icon=&#8221;true&#8221; accent_color=&#8221;#bababa&#8221; i_custom_color=&#8221;#bababa&#8221;][vc_custom_heading text=&#8221;Familial Exudative Vitreoretinopathy &#8211; Clinical Case 1&#8243; font_container=&#8221;tag:h1|text_align:center|color:%235f1b52&#8243; use_theme_fonts=&#8221;yes&#8221; link=&#8221;url:https%3A%2F%2Fwww.atlasrleye.com%2Fen%2Ffamilial-exudative-vitreoretinopathy%2F|title:%20Familial%20Exudative%20Vitreoretinopathy%20|&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row][vc_row gap=&#8221;35&#8243; equal_height=&#8221;yes&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;4959&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][vc_column_inner [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":71861,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-71865","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/71865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/comments?post=71865"}],"version-history":[{"count":35,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/71865\/revisions"}],"predecessor-version":[{"id":112939,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/71865\/revisions\/112939"}],"up":[{"embeddable":true,"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/pages\/71861"}],"wp:attachment":[{"href":"https:\/\/www.atlasrleye.com\/en\/wp-json\/wp\/v2\/media?parent=71865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}